{"id":8722,"date":"2022-11-15T15:00:44","date_gmt":"2022-11-15T15:00:44","guid":{"rendered":"http:\/\/ludwig-witzani.de\/?page_id=8722"},"modified":"2025-06-03T10:32:50","modified_gmt":"2025-06-03T10:32:50","slug":"australien-drei-reisen-zu-den-antipoden","status":"publish","type":"page","link":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/","title":{"rendered":"Australien. Drei Reisen zu den Antipoden"},"content":{"rendered":"<h5><a href=\"http:\/\/ludwig-witzani.de\/wp-content\/uploads\/2022\/11\/01-Inhaltsverzeichnis-und-Vorwort.pdf\">01 Inhaltsverzeichnis und Vorwort<\/a><\/h5>\n<h5><strong><a href=\"http:\/\/ludwig-witzani.de\/wp-content\/uploads\/2023\/01\/02-Ayers-Rock.pdf\">02 Ayers Rock<\/a><\/strong><\/h5>\n<h5><strong><a href=\"http:\/\/ludwig-witzani.de\/wp-content\/uploads\/2023\/01\/03-Der-lange-Weg-nach-Karijini.pdf\">03 Der lange Weg nach Karijini<\/a><\/strong><\/h5>\n<h5><a href=\"http:\/\/ludwig-witzani.de\/bildergalerie-australien\/\">Bildergalerie AUSTRALIEN<\/a><\/h5>\n<p><em>Hier erh\u00e4ltlch: <\/em><\/p>\n<p><em><strong>Printausgabe<\/strong>: 356 Seiten, 16,95 Euro epubli, Berlin, 2023, <\/em><a href=\"https:\/\/www.amazon.de\/Weltreisen-Australien-Drei-Reisen-Antipoden\/dp\/3757511670\/ref=sr_1_2?__mk_de_DE=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=Z3OAQ2BMX142&amp;keywords=Ludwig+Witzani+Australien&amp;qid=1675926261&amp;sprefix=ludwig+witzani+australien%2Caps%2C81&amp;sr=8-2\">Weltreisen \/ Australien: Drei Reisen zu den Antipoden : PRINT <\/a><em>&nbsp;&nbsp;<\/em><\/p>\n<p><em><strong>EBook<\/strong> 5,99 Euro, epubli, Berlin 2023,&nbsp; ISBN 978-3-753156-16-3&nbsp;<\/em><a href=\"https:\/\/www.amazon.de\/dp\/B0BV925Y1V\/ref=sr_1_1?__mk_de_DE=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=2O7OYILR5ZED3&amp;keywords=Ludwig+Witzani+Australien&amp;qid=1675926324&amp;sprefix=ludwig+witzani+australien%2Caps%2C93&amp;sr=8-1\">Australien: Drei Reisen zu den Antipoden eBook<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>01 Inhaltsverzeichnis und Vorwort 02 Ayers Rock 03 Der lange Weg nach Karijini Bildergalerie AUSTRALIEN Hier erh\u00e4ltlch: Printausgabe: 356 Seiten, 16,95 Euro epubli, Berlin, 2023, Weltreisen \/ Australien: Drei Reisen zu den Antipoden : PRINT &nbsp;&nbsp; EBook 5,99 Euro, epubli, Berlin 2023,&nbsp; ISBN 978-3-753156-16-3&nbsp;Australien: Drei Reisen zu den Antipoden eBook &nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &hellip; <a href=\"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/\" class=\"more-link\"><span class=\"screen-reader-text\">Australien. Drei Reisen zu den Antipoden<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-8722","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Australien. Drei Reisen zu den Antipoden - Ludwig Witzani<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Australien. Drei Reisen zu den Antipoden - Ludwig Witzani\" \/>\n<meta property=\"og:description\" content=\"01 Inhaltsverzeichnis und Vorwort 02 Ayers Rock 03 Der lange Weg nach Karijini Bildergalerie AUSTRALIEN Hier erh\u00e4ltlch: Printausgabe: 356 Seiten, 16,95 Euro epubli, Berlin, 2023, Weltreisen \/ Australien: Drei Reisen zu den Antipoden : PRINT &nbsp;&nbsp; EBook 5,99 Euro, epubli, Berlin 2023,&nbsp; ISBN 978-3-753156-16-3&nbsp;Australien: Drei Reisen zu den Antipoden eBook &nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &hellip; Australien. Drei Reisen zu den Antipoden weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/\" \/>\n<meta property=\"og:site_name\" content=\"Ludwig Witzani\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-03T10:32:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/australien-drei-reisen-zu-den-antipoden\\\/\",\"url\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/australien-drei-reisen-zu-den-antipoden\\\/\",\"name\":\"Australien. Drei Reisen zu den Antipoden - Ludwig Witzani\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/#website\"},\"datePublished\":\"2022-11-15T15:00:44+00:00\",\"dateModified\":\"2025-06-03T10:32:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/australien-drei-reisen-zu-den-antipoden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/australien-drei-reisen-zu-den-antipoden\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/australien-drei-reisen-zu-den-antipoden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Australien. Drei Reisen zu den Antipoden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/#website\",\"url\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/\",\"name\":\"Ludwig Witzani\",\"description\":\"World Wide Travel\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ludwig-witzani.de\\\/zu-den-grossen-traeumen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Australien. Drei Reisen zu den Antipoden - Ludwig Witzani","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/","og_locale":"de_DE","og_type":"article","og_title":"Australien. Drei Reisen zu den Antipoden - Ludwig Witzani","og_description":"01 Inhaltsverzeichnis und Vorwort 02 Ayers Rock 03 Der lange Weg nach Karijini Bildergalerie AUSTRALIEN Hier erh\u00e4ltlch: Printausgabe: 356 Seiten, 16,95 Euro epubli, Berlin, 2023, Weltreisen \/ Australien: Drei Reisen zu den Antipoden : PRINT &nbsp;&nbsp; EBook 5,99 Euro, epubli, Berlin 2023,&nbsp; ISBN 978-3-753156-16-3&nbsp;Australien: Drei Reisen zu den Antipoden eBook &nbsp; &nbsp;&nbsp; &nbsp; &nbsp; &nbsp; &hellip; Australien. Drei Reisen zu den Antipoden weiterlesen &rarr;","og_url":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/","og_site_name":"Ludwig Witzani","article_modified_time":"2025-06-03T10:32:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/","url":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/","name":"Australien. Drei Reisen zu den Antipoden - Ludwig Witzani","isPartOf":{"@id":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/#website"},"datePublished":"2022-11-15T15:00:44+00:00","dateModified":"2025-06-03T10:32:50+00:00","breadcrumb":{"@id":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/australien-drei-reisen-zu-den-antipoden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/"},{"@type":"ListItem","position":2,"name":"Australien. Drei Reisen zu den Antipoden"}]},{"@type":"WebSite","@id":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/#website","url":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/","name":"Ludwig Witzani","description":"World Wide Travel","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P4daYo-2gG","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/wp-json\/wp\/v2\/pages\/8722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/wp-json\/wp\/v2\/comments?post=8722"}],"version-history":[{"count":18,"href":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/wp-json\/wp\/v2\/pages\/8722\/revisions"}],"predecessor-version":[{"id":8835,"href":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/wp-json\/wp\/v2\/pages\/8722\/revisions\/8835"}],"wp:attachment":[{"href":"https:\/\/ludwig-witzani.de\/zu-den-grossen-traeumen\/wp-json\/wp\/v2\/media?parent=8722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}